 {"id":8818,"date":"2017-05-29T17:25:35","date_gmt":"2017-05-29T17:25:35","guid":{"rendered":"http:\/\/www.capitolina.com\/wp\/?p=8818"},"modified":"2017-05-29T18:05:02","modified_gmt":"2017-05-29T18:05:02","slug":"flaggers-a-firenze","status":"publish","type":"post","link":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/","title":{"rendered":"Flaggers a Firenze"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div><a href=\"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/img-20170529-wa0001-1\/\" rel=\"attachment wp-att-8821\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-8821 alignleft\" src=\"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-300x180.jpg\" alt=\"IMG-20170529-WA0001 (1)\" width=\"300\" height=\"180\" \/><\/a>Era dal 22 aprile che aspettavamo di rendere la visita alle Taccovale Florentia e finalmente, dopo poco pi\u00f9 di un mese, eccoci a Firenze.<\/div>\n<p>Tredici le mamme disponibili in questa trasferta iniziata per alcune dal venerd\u00ec con viaggio in pulmino della Capitolina, per altre il sabato mattina.<\/p>\n<\/div>\n<p>Per dirla alla Martino, &#8220;le pazze Flaggers&#8221; arrivano al campo dellla Florentia per le 9,30 mentre \u00e8 in allestimento la manifestazione &#8220;Florentia in Medioevo&#8221; e c&#8217;\u00e8 tutto il tempo di preparare bene gli incontri che andremo a fare infatti, oltre alle fiorentine, ci sono le Iene di Novara.<\/p>\n<\/div>\n<p>Fa caldo, delle due squadre che prevedevamo di mettere in campo, in realt\u00e0 ne mettiamo in campo una sola facendo ruotare tutte e tredici.<\/p>\n<\/div>\n<p>L&#8217;ingresso in campo \u00e8 molto folkloristico tra due ali di u.6 che hanno giocato nella prima mattinata e siamo subito noi ad aprire le danze con le viola.<\/p>\n<\/div>\n<p>Il divertirsi l&#8217;obiettivo fondamentale ma, man mano che si gioca, emerge l&#8217;anima agonista di chi scende in campo per non fare da comparsa.<\/p>\n<\/div>\n<p>E allora ci alterniamo presentando un gioco piacevole a vedersi ma che difetta ancora in velocit\u00e0 e, se vogliamo essere anche tecnici, di larghezza e profondit\u00e0 in attacco mentre in difesa, ogni tanto qualcuna delle nostre si dimentica di avanzare offrendo il fianco alle frecce avversarie.<\/p>\n<\/div>\n<p>L&#8217;acqua ed uno spicchio di ombra l&#8217;unico momento di respiro in una mattina che scivola, partita dopo partita, verso l&#8217;ora di pranzo.<\/p>\n<\/div>\n<p>Anche il tempo, durante la partita di rugby a sette tra Florentia e Iene di un esordio assoluto della nostra flagger Federica!<\/p>\n<\/div>\n<p>Foto di gruppo tra tutte le ragazze al termine della mattinata con le magliette intrise di sudore e polvere ma veramente soddisfatte di avere vissuto una giornata cos\u00ec. Una doccia toglistanchezza ed un sontuoso terzo tempo a base di verdure mette in pace tutti gli animi e ci porta al momento dello scambio dei doni tra le capitane e alla premiazione con tanto di medaglia al cospetto degli sbandieratori di Firenze.<\/p>\n<\/div>\n<p>Bene, possiamo veramente dire di avere vissuto una giornata che ci rimarr\u00e0 nella memoria delle belle cose e che, d&#8217;accordo con le Taccovale,splendide ospiti, \u00e8 solo l&#8217;inizio di un&#8217;amicizia sportiva che \u00e8 gi\u00e0 diventata una tradizione.<\/p>\n<div><\/div>\n<p><span style=\"color: #212121; font-family: wf_segoe-ui_semibold, 'Segoe UI Semibold', 'Segoe WP Semibold', 'Segoe UI', 'Segoe WP', Tahoma, Arial, sans-serif; font-size: 15px;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era dal 22 aprile che aspettavamo di rendere la visita alle Taccovale Florentia e finalmente, dopo poco pi\u00f9 di un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[34,1],"tags":[],"class_list":["post-8818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996\" \/>\n<meta property=\"og:description\" content=\"Era dal 22 aprile che aspettavamo di rendere la visita alle Taccovale Florentia e finalmente, dopo poco pi\u00f9 di un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Unione Rugby Capitolina - Il Rugby a Roma dal 1996\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-29T17:25:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-29T18:05:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"333\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alessandro Martire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro Martire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/\"},\"author\":{\"name\":\"Alessandro Martire\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#\\\/schema\\\/person\\\/0dd0670ab7d4379c9388811c4635545f\"},\"headline\":\"Flaggers a Firenze\",\"datePublished\":\"2017-05-29T17:25:35+00:00\",\"dateModified\":\"2017-05-29T18:05:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/\"},\"wordCount\":374,\"publisher\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IMG-20170529-WA0001-1-e1560969637670.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/\",\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/\",\"name\":\"Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IMG-20170529-WA0001-1-e1560969637670.jpg\",\"datePublished\":\"2017-05-29T17:25:35+00:00\",\"dateModified\":\"2017-05-29T18:05:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IMG-20170529-WA0001-1-e1560969637670.jpg\",\"contentUrl\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IMG-20170529-WA0001-1-e1560969637670.jpg\",\"width\":333,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/flaggers-a-firenze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flaggers a Firenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/\",\"name\":\"Unione Rugby Capitolina - Il Rugby a Roma dal 1996\",\"description\":\"Il Rugby a Roma dal 1996\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#organization\",\"name\":\"Unione Rugby Capitolina\",\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Logo-URC-tondo-copy2.png\",\"contentUrl\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Logo-URC-tondo-copy2.png\",\"width\":360,\"height\":360,\"caption\":\"Unione Rugby Capitolina\"},\"image\":{\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/#\\\/schema\\\/person\\\/0dd0670ab7d4379c9388811c4635545f\",\"name\":\"Alessandro Martire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g\",\"caption\":\"Alessandro Martire\"},\"url\":\"https:\\\/\\\/www.capitolina.com\\\/wp\\\/author\\\/alessandro-martire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/","og_locale":"it_IT","og_type":"article","og_title":"Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996","og_description":"Era dal 22 aprile che aspettavamo di rendere la visita alle Taccovale Florentia e finalmente, dopo poco pi\u00f9 di un [&hellip;]","og_url":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/","og_site_name":"Unione Rugby Capitolina - Il Rugby a Roma dal 1996","article_published_time":"2017-05-29T17:25:35+00:00","article_modified_time":"2017-05-29T18:05:02+00:00","og_image":[{"width":333,"height":200,"url":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg","type":"image\/jpeg"}],"author":"Alessandro Martire","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alessandro Martire","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#article","isPartOf":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/"},"author":{"name":"Alessandro Martire","@id":"https:\/\/www.capitolina.com\/wp\/#\/schema\/person\/0dd0670ab7d4379c9388811c4635545f"},"headline":"Flaggers a Firenze","datePublished":"2017-05-29T17:25:35+00:00","dateModified":"2017-05-29T18:05:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/"},"wordCount":374,"publisher":{"@id":"https:\/\/www.capitolina.com\/wp\/#organization"},"image":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/","url":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/","name":"Flaggers a Firenze - Unione Rugby Capitolina - Il Rugby a Roma dal 1996","isPartOf":{"@id":"https:\/\/www.capitolina.com\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#primaryimage"},"image":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg","datePublished":"2017-05-29T17:25:35+00:00","dateModified":"2017-05-29T18:05:02+00:00","breadcrumb":{"@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#primaryimage","url":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg","contentUrl":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg","width":333,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.capitolina.com\/wp\/flaggers-a-firenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.capitolina.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Flaggers a Firenze"}]},{"@type":"WebSite","@id":"https:\/\/www.capitolina.com\/wp\/#website","url":"https:\/\/www.capitolina.com\/wp\/","name":"Unione Rugby Capitolina - Il Rugby a Roma dal 1996","description":"Il Rugby a Roma dal 1996","publisher":{"@id":"https:\/\/www.capitolina.com\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.capitolina.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.capitolina.com\/wp\/#organization","name":"Unione Rugby Capitolina","url":"https:\/\/www.capitolina.com\/wp\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.capitolina.com\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2019\/09\/Logo-URC-tondo-copy2.png","contentUrl":"https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2019\/09\/Logo-URC-tondo-copy2.png","width":360,"height":360,"caption":"Unione Rugby Capitolina"},"image":{"@id":"https:\/\/www.capitolina.com\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.capitolina.com\/wp\/#\/schema\/person\/0dd0670ab7d4379c9388811c4635545f","name":"Alessandro Martire","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22223e1861dffde7f48d885f9c472f4e36a80800253f17b54d61a202ae8386bf?s=96&d=mm&r=g","caption":"Alessandro Martire"},"url":"https:\/\/www.capitolina.com\/wp\/author\/alessandro-martire\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg",333,200,false],"thumbnail":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-150x90.jpg",150,90,true],"medium":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-300x180.jpg",300,180,true],"medium_large":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg",333,200,false],"large":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-1024x615.jpg",1024,615,true],"1536x1536":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg",333,200,false],"2048x2048":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg",333,200,false],"mailpoet_newsletter_max":["https:\/\/www.capitolina.com\/wp\/wp-content\/uploads\/2017\/05\/IMG-20170529-WA0001-1-e1560969637670.jpg",333,200,false]},"uagb_author_info":{"display_name":"Alessandro Martire","author_link":"https:\/\/www.capitolina.com\/wp\/author\/alessandro-martire\/"},"uagb_comment_info":0,"uagb_excerpt":"Era dal 22 aprile che aspettavamo di rendere la visita alle Taccovale Florentia e finalmente, dopo poco pi\u00f9 di un [&hellip;]","_links":{"self":[{"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/posts\/8818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/comments?post=8818"}],"version-history":[{"count":4,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/posts\/8818\/revisions"}],"predecessor-version":[{"id":8823,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/posts\/8818\/revisions\/8823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/media\/8821"}],"wp:attachment":[{"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/media?parent=8818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/categories?post=8818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capitolina.com\/wp\/wp-json\/wp\/v2\/tags?post=8818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}